{"id":23975,"date":"2025-11-05T19:33:57","date_gmt":"2025-11-06T03:33:57","guid":{"rendered":"https:\/\/wou.edu\/westernhowl\/?p=23975"},"modified":"2025-11-05T19:34:51","modified_gmt":"2025-11-06T03:34:51","slug":"el-huracan-melissa-golpea","status":"publish","type":"post","link":"https:\/\/wou.edu\/westernhowl\/el-huracan-melissa-golpea\/","title":{"rendered":"El hurac\u00e1n Melissa golpea"},"content":{"rendered":"\n<p><span style=\"font-weight: 400\">5 de noviembre del 2025 | Abbi Duhart | Editora de Noticias<\/span><\/p>\n<p><span style=\"font-weight: 400\">El hurac\u00e1n Melissa es uno de los huracanes m\u00e1s poderosos que se han registrado en el oc\u00e9ano Atl\u00e1ntico hasta la fecha, tras arrasar el norte del Caribe y dejar a miles de personas sin electricidad ni hogar. Cuando el hurac\u00e1n lleg\u00f3 a Jamaica el 28 de octubre, se report\u00f3 como un hurac\u00e1n de categor\u00eda 5 con vientos de hasta 185 mph. Un hurac\u00e1n de categor\u00eda 5 es la clasificaci\u00f3n m\u00e1s alta para huracanes e implica vientos de 157 mph o m\u00e1s, adem\u00e1s de causar da\u00f1os catastr\u00f3ficos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">El 30 de octubre, el hurac\u00e1n azot\u00f3 Jamaica y caus\u00f3 una destrucci\u00f3n masiva, afectando a los residentes e incluso cobr\u00e1ndose vidas. Muchos residentes se quedaron sin hogar tras la tormenta, y muchos perdieron sus pertenencias personales debido a las inundaciones. La tormenta tambi\u00e9n arras\u00f3 carreteras y puentes, lo que dificult\u00f3 que los jamaicanos recibieran ayuda tras el impacto. Finalmente, helic\u00f3pteros llegaron para distribuir alimentos, agua, medicinas y otros suministros esenciales. Tras el desastre, los equipos de b\u00fasqueda y rescate encontraron al menos 19 muertos, y m\u00e1s de 13,000 personas permanecen en refugios superpoblados tras haber perdido sus hogares. El setenta y dos por ciento de la isla se qued\u00f3 sin electricidad.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Da\u00f1os similares se produjeron en Cuba, pero la Defensa Civil cubana logr\u00f3 evacuar a 735,000 personas antes de que la tormenta tocara tierra.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Hait\u00ed tambi\u00e9n se vio gravemente afectado por el hurac\u00e1n Melissa, con al menos 30 fallecidos y 20 residentes reportados como desaparecidos. Puerto Pr\u00edncipe, la capital, sufri\u00f3 algunos de los da\u00f1os m\u00e1s severos. El hurac\u00e1n Melissa provoc\u00f3 fuertes lluvias que inundaron gran parte del territorio y dejaron viviendas inaccesibles. Los residentes comenzaron a regresar a sus hogares lentamente el 30 de octubre. El hurac\u00e1n destruy\u00f3 viviendas y separ\u00f3 familias, y se reportaron casos de ni\u00f1os fallecidos. M\u00e1s de 15,000 personas se alojaron en refugios tras el paso del hurac\u00e1n. En Hait\u00ed y Cuba, la tremenda cantidad de lluvia e inundaciones dej\u00f3 comunidades con cientos de residentes completamente aislados, sin forma de contactar a nadie para pedir ayuda.<\/span><\/p>\n<p><span style=\"font-weight: 400\">El hurac\u00e1n Melissa caus\u00f3 al menos 50 muertes en Jamaica, Hait\u00ed y Cuba, pero se espera que esta cifra aumente a medida que los expertos contin\u00faan la b\u00fasqueda de las personas desaparecidas en las islas. Tras estos devastadores sucesos, el hurac\u00e1n Melissa se alej\u00f3 de las Bermudas la ma\u00f1ana del 31 de octubre, debilit\u00e1ndose a hurac\u00e1n de categor\u00eda 1. Hacia las 11 a.m., la tormenta se hab\u00eda debilitado y se clasific\u00f3 como un potente cicl\u00f3n postropical con vientos de alrededor de 85 mph, desplaz\u00e1ndose hacia el noreste. A medida que la tormenta continuaba en esta direcci\u00f3n, se esperaba que la costa noreste de Estados Unidos y partes de Canad\u00e1 se vieran afectadas, principalmente por fuertes lluvias. Si bien probablemente no causar\u00e1 los mismos da\u00f1os en tierra que en las zonas mencionadas, la tormenta s\u00ed generar\u00e1 condiciones mar\u00edtimas adversas cerca de la costa.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Contacta al autor en howlnews@mail.wou.edu<\/span><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1652,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"El hurac\u00e1n Melissa golpea","_seopress_titles_desc":"Los devastadores da\u00f1os causados por el hurac\u00e1n Melissa en el Caribe","_seopress_robots_index":"","_lmt_disableupdate":"no","_lmt_disable":"","_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[6735,6922],"tags":[7419,7409,1178,7412,7423,7422,7424,7082,7414,7420,7413,7298,7077,7421,7406,7407,7426,7425,7427,7073,7070,4136,7408,7411,7410,7418,7417,7416,7415,684,39],"class_list":["post-23975","post","type-post","status-publish","format-standard","hentry","category-espanol","category-noticias-de-2025-2026","tag-agua","tag-atlantico","tag-campus","tag-caribe","tag-ciclon","tag-consecuencias","tag-costa","tag-cuba","tag-danos","tag-desaparecidos","tag-energia","tag-estudiantes","tag-haiti","tag-helicoptero","tag-huracan","tag-huracan-melissa","tag-inundacion","tag-inundar","tag-isla","tag-jamaica","tag-melissa","tag-muerte","tag-nivel-cinco","tag-oceano","tag-oceano-atlantico","tag-residentes","tag-tormenta","tag-velocidad","tag-viento","tag-western","tag-wou"],"modified_by":"The Howl Spanish Translator","_links":{"self":[{"href":"https:\/\/wou.edu\/westernhowl\/wp-json\/wp\/v2\/posts\/23975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wou.edu\/westernhowl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wou.edu\/westernhowl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wou.edu\/westernhowl\/wp-json\/wp\/v2\/users\/1652"}],"replies":[{"embeddable":true,"href":"https:\/\/wou.edu\/westernhowl\/wp-json\/wp\/v2\/comments?post=23975"}],"version-history":[{"count":1,"href":"https:\/\/wou.edu\/westernhowl\/wp-json\/wp\/v2\/posts\/23975\/revisions"}],"predecessor-version":[{"id":23978,"href":"https:\/\/wou.edu\/westernhowl\/wp-json\/wp\/v2\/posts\/23975\/revisions\/23978"}],"wp:attachment":[{"href":"https:\/\/wou.edu\/westernhowl\/wp-json\/wp\/v2\/media?parent=23975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wou.edu\/westernhowl\/wp-json\/wp\/v2\/categories?post=23975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wou.edu\/westernhowl\/wp-json\/wp\/v2\/tags?post=23975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}